{"id":2104,"date":"2022-05-06T13:42:14","date_gmt":"2022-05-06T11:42:14","guid":{"rendered":"https:\/\/valentojobs.com\/?post_type=vacature&#038;p=2104"},"modified":"2026-07-14T09:53:14","modified_gmt":"2026-07-14T07:53:14","slug":"schoonmaak-medewerker","status":"publish","type":"vacature","link":"https:\/\/valentojobs.com\/pl\/vacature\/schoonmaak-medewerker\/","title":{"rendered":"Sprzatanie"},"content":{"rendered":"","protected":false},"featured_media":3416,"parent":0,"menu_order":0,"template":"","format":"standard","arbeidsuren":[225],"locatie":[227,174,228,229,124,226,110,145,92],"opdrachtgever":[],"opleiding":[107],"ploegendienst":[],"recruiter":[149],"salarisrange":[197],"sector":[111],"soort_dienstverband":[13],"class_list":["post-2104","vacature","type-vacature","status-publish","format-standard","has-post-thumbnail","hentry","arbeidsuren-fulltime","locatie-echt-susteren","locatie-eindhoven","locatie-heerlen-parkstad","locatie-maastricht-heuvelland","locatie-roermond","locatie-sittard-geleen","locatie-venlo","locatie-verschillende-locaties","locatie-weert","opleiding-n-v-t","recruiter-beata-dygasiewicz","salarisrange-e-2-500-e-3-000","sector-overige","soort_dienstverband-onbepaalde-tijd"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schoonmaakmedewerk(st)er - Valento | Vacatures Bouw &amp; Techniek<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/valentojobs.com\/pl\/vacature\/schoonmaak-medewerker\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schoonmaakmedewerk(st)er - Valento | Vacatures Bouw &amp; Techniek\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valentojobs.com\/pl\/vacature\/schoonmaak-medewerker\/\" \/>\n<meta property=\"og:site_name\" content=\"Valento | Vacatures Bouw &amp; Techniek\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/valentojobs\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T07:53:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valentojobs.com\/wp-content\/uploads\/2022\/05\/schoonmaak-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/\",\"url\":\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/\",\"name\":\"Schoonmaakmedewerk(st)er - Valento | Vacatures Bouw &amp; Techniek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/valentojobs.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/valentojobs.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/schoonmaak-1.jpg\",\"datePublished\":\"2022-05-06T11:42:14+00:00\",\"dateModified\":\"2026-07-14T07:53:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/#primaryimage\",\"url\":\"https:\\\/\\\/valentojobs.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/schoonmaak-1.jpg\",\"contentUrl\":\"https:\\\/\\\/valentojobs.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/schoonmaak-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/valentojobs.com\\\/vacature\\\/schoonmaak-medewerker\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/valentojobs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schoonmaakmedewerk(st)er\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/valentojobs.com\\\/#website\",\"url\":\"https:\\\/\\\/valentojobs.com\\\/\",\"name\":\"Valento | Vacatures Bouw &amp; Techniek\",\"description\":\"Vacatures in de bouw in Limburg\",\"publisher\":{\"@id\":\"https:\\\/\\\/valentojobs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/valentojobs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/valentojobs.com\\\/#organization\",\"name\":\"Valento Jobs B.V.\",\"url\":\"https:\\\/\\\/valentojobs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/valentojobs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/valentojobs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/valentojobs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Valento Jobs B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/valentojobs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/valentojobs\",\"https:\\\/\\\/www.instagram.com\\\/valento_jobs\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/valento\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pracownik sprz\u0105taj\u0105cy - Valento | Oferty pracy Budownictwo i in\u017cynieria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/valentojobs.com\/pl\/vacature\/schoonmaak-medewerker\/","og_locale":"pl_PL","og_type":"article","og_title":"Schoonmaakmedewerk(st)er - Valento | Vacatures Bouw &amp; Techniek","og_url":"https:\/\/valentojobs.com\/pl\/vacature\/schoonmaak-medewerker\/","og_site_name":"Valento | Vacatures Bouw &amp; Techniek","article_publisher":"https:\/\/www.facebook.com\/valentojobs","article_modified_time":"2026-07-14T07:53:14+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/valentojobs.com\/wp-content\/uploads\/2022\/05\/schoonmaak-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/","url":"https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/","name":"Pracownik sprz\u0105taj\u0105cy - Valento | Oferty pracy Budownictwo i in\u017cynieria","isPartOf":{"@id":"https:\/\/valentojobs.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/#primaryimage"},"image":{"@id":"https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/#primaryimage"},"thumbnailUrl":"https:\/\/valentojobs.com\/wp-content\/uploads\/2022\/05\/schoonmaak-1.jpg","datePublished":"2022-05-06T11:42:14+00:00","dateModified":"2026-07-14T07:53:14+00:00","breadcrumb":{"@id":"https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/#primaryimage","url":"https:\/\/valentojobs.com\/wp-content\/uploads\/2022\/05\/schoonmaak-1.jpg","contentUrl":"https:\/\/valentojobs.com\/wp-content\/uploads\/2022\/05\/schoonmaak-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/valentojobs.com\/vacature\/schoonmaak-medewerker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/valentojobs.com\/"},{"@type":"ListItem","position":2,"name":"Schoonmaakmedewerk(st)er"}]},{"@type":"WebSite","@id":"https:\/\/valentojobs.com\/#website","url":"https:\/\/valentojobs.com\/","name":"Valento | Wakacje Budownictwo i In\u017cynieria","description":"Oferty pracy w bran\u017cy budowlanej w Limburgii","publisher":{"@id":"https:\/\/valentojobs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valentojobs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/valentojobs.com\/#organization","name":"Valento Jobs B.V.","url":"https:\/\/valentojobs.com\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/valentojobs.com\/#\/schema\/logo\/image\/","url":"https:\/\/valentojobs.com\/wp-content\/uploads\/2022\/01\/logo.svg","contentUrl":"https:\/\/valentojobs.com\/wp-content\/uploads\/2022\/01\/logo.svg","width":"1024","height":"1024","caption":"Valento Jobs B.V."},"image":{"@id":"https:\/\/valentojobs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/valentojobs","https:\/\/www.instagram.com\/valento_jobs\/","https:\/\/www.linkedin.com\/company\/valento\/"]}]}},"_links":{"self":[{"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/vacature\/2104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/vacature"}],"about":[{"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/types\/vacature"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/media\/3416"}],"wp:attachment":[{"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/media?parent=2104"}],"wp:term":[{"taxonomy":"arbeidsuren","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/arbeidsuren?post=2104"},{"taxonomy":"locatie","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/locatie?post=2104"},{"taxonomy":"opdrachtgever","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/opdrachtgever?post=2104"},{"taxonomy":"opleiding","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/opleiding?post=2104"},{"taxonomy":"ploegendienst","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/ploegendienst?post=2104"},{"taxonomy":"recruiter","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/recruiter?post=2104"},{"taxonomy":"salarisrange","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/salarisrange?post=2104"},{"taxonomy":"sector","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/sector?post=2104"},{"taxonomy":"soort_dienstverband","embeddable":true,"href":"https:\/\/valentojobs.com\/pl\/wp-json\/wp\/v2\/soort_dienstverband?post=2104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}